{"id":468,"count":3,"description":"","link":"https:\/\/bensbargains.com\/thecheckout\/tag\/online-gaming\/","name":"online gaming","slug":"online-gaming","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bensbargains.com\/thecheckout\/wp-json\/wp\/v2\/tags\/468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bensbargains.com\/thecheckout\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bensbargains.com\/thecheckout\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bensbargains.com\/thecheckout\/wp-json\/wp\/v2\/posts?tags=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}