{"id":1356,"count":2,"description":"","link":"https:\/\/bensbargains.com\/thecheckout\/tag\/deadpool\/","name":"Deadpool","slug":"deadpool","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bensbargains.com\/thecheckout\/wp-json\/wp\/v2\/tags\/1356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bensbargains.com\/thecheckout\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bensbargains.com\/thecheckout\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bensbargains.com\/thecheckout\/wp-json\/wp\/v2\/posts?tags=1356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}